{"id":10802,"date":"2017-06-26T08:11:24","date_gmt":"2017-06-26T07:11:24","guid":{"rendered":"https:\/\/www.salvioniarredamenti.it\/projects\/"},"modified":"2024-06-24T16:28:15","modified_gmt":"2024-06-24T15:28:15","slug":"progetti-realizzazioni-salvioni","status":"publish","type":"page","link":"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/","title":{"rendered":"Progetti"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":107,"comment_status":"closed","ping_status":"closed","template":"page-projects.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-10802","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Progetti - Le realizzazioni di Salvioni Design Solutions<\/title>\n<meta name=\"description\" content=\"Salvioni si avvale di un team di architetti e interior designer per la realizzazione di progetti abitativi pubblici e privati in tutto il mondo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progetti - Le realizzazioni di Salvioni Design Solutions\" \/>\n<meta property=\"og:description\" content=\"Salvioni si avvale di un team di architetti e interior designer per la realizzazione di progetti abitativi pubblici e privati in tutto il mondo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Salvioni\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-24T15:28:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/\",\"url\":\"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/\",\"name\":\"Progetti - Le realizzazioni di Salvioni Design Solutions\",\"isPartOf\":{\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#website\"},\"datePublished\":\"2017-06-26T07:11:24+00:00\",\"dateModified\":\"2024-06-24T15:28:15+00:00\",\"description\":\"Salvioni si avvale di un team di architetti e interior designer per la realizzazione di progetti abitativi pubblici e privati in tutto il mondo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salvioniarredamenti.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#website\",\"url\":\"https:\/\/www.salvioniarredamenti.it\/en\/\",\"name\":\"Salvioni\",\"description\":\"Salvioni Arredamenti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salvioniarredamenti.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Progetti - Le realizzazioni di Salvioni Design Solutions","description":"Salvioni si avvale di un team di architetti e interior designer per la realizzazione di progetti abitativi pubblici e privati in tutto il mondo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/","og_locale":"it_IT","og_type":"article","og_title":"Progetti - Le realizzazioni di Salvioni Design Solutions","og_description":"Salvioni si avvale di un team di architetti e interior designer per la realizzazione di progetti abitativi pubblici e privati in tutto il mondo.","og_url":"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/","og_site_name":"Salvioni","article_modified_time":"2024-06-24T15:28:15+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/","url":"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/","name":"Progetti - Le realizzazioni di Salvioni Design Solutions","isPartOf":{"@id":"https:\/\/www.salvioniarredamenti.it\/en\/#website"},"datePublished":"2017-06-26T07:11:24+00:00","dateModified":"2024-06-24T15:28:15+00:00","description":"Salvioni si avvale di un team di architetti e interior designer per la realizzazione di progetti abitativi pubblici e privati in tutto il mondo.","breadcrumb":{"@id":"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.salvioniarredamenti.it\/it\/progetti-realizzazioni-salvioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salvioniarredamenti.it\/it\/"},{"@type":"ListItem","position":2,"name":"Progetti"}]},{"@type":"WebSite","@id":"https:\/\/www.salvioniarredamenti.it\/en\/#website","url":"https:\/\/www.salvioniarredamenti.it\/en\/","name":"Salvioni","description":"Salvioni Arredamenti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salvioniarredamenti.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/pages\/10802"}],"collection":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/comments?post=10802"}],"version-history":[{"count":11,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/pages\/10802\/revisions"}],"predecessor-version":[{"id":59932,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/pages\/10802\/revisions\/59932"}],"wp:attachment":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/media?parent=10802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}