{"id":16240,"date":"2018-04-17T15:04:43","date_gmt":"2018-04-17T15:04:43","guid":{"rendered":"https:\/\/www.salvioniarredamenti.it\/?p=16240\/"},"modified":"2022-12-30T16:13:03","modified_gmt":"2022-12-30T16:13:03","slug":"miart-2018","status":"publish","type":"post","link":"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/","title":{"rendered":"Miart 2018 &#8211; La mostra &#8220;Serie Armonica Alternata&#8221;"},"content":{"rendered":"<p>Venerd\u00ec 13 e sabato 14 Aprile ha avuto luogo presso lo showroom Milano Durini la mostra<strong> &#8220;Serie Armonica Alternata&#8221;<\/strong>, promossa dalla <strong>galleria d&#8217;arte Barbara Paci di Pietrasanta<\/strong>. L&#8217;esposizione, completa di una serie di opere d&#8217;arte degli artisti\u00a0<strong>Massimiliano Pelletti e Alessandro Busci<\/strong>, nasce dalla teoria matematica secondo cui la somma dei reciproci di tutti i numeri naturali abbia come risultato l&#8217;infinito. Partendo da questo concetto, i due artisti hanno collaborato dando vita a un paesaggio unico e surreale, animato da busti e volti in pietra alternati a tele astratte e d&#8217;ispirazione fortemente emotiva. L&#8217;ambiente risultante si definisce quindi con una perfetta sincronia di opposti la cui attrazione risiede proprio nella differente entit\u00e0 che li contraddistingue. Dimora dell&#8217;arredo di design, Salvioni Design Solutions ha accolto questa ispirazione disegnandovi attorno il proprio tocco personale: eleganza e personalit\u00e0, gusto e cura del dettaglio nonch\u00e9 un&#8217;esclusiva serata inaugurale presso lo\u00a0<strong>showroom Milano Durini.<\/strong>\u00a0Per l&#8217;occasione, lo store milanese\u00a0ha aperto le proprie porte ad artisti, critici d&#8217;arte e appassionati da tutto il mondo ricreando per loro un&#8217;ambiente di grande suggestione nel nuovissimo piano &#8220;Milano Velata&#8221; allestito ad hoc.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Venerd\u00ec 13 e sabato 14 Aprile ha avuto luogo presso lo showroom Milano Durini la mostra &#8220;Serie Armonica Alternata&#8221;, promossa dalla galleria d&#8217;arte Barbara Paci di Pietrasanta. L&#8217;esposizione, completa di una serie di opere d&#8217;arte degli artisti\u00a0Massimiliano Pelletti e Alessandro Busci, nasce dalla teoria matematica secondo cui la somma dei reciproci di tutti i numeri [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[962],"tags":[],"class_list":["post-16240","post","type-post","status-publish","format-standard","hentry","category-showroom"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Miart 2018 - Galleria d&#039;Arte Barbara e Salvioni Design Solutions<\/title>\n<meta name=\"description\" content=\"Salvioni ha ospitato la mostra &quot;Serie Armonica Alternata&quot; promossa dalla Galleria d&#039;Arte Barbara Paci di Pietrasanta in occasione del MIART 2018\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miart 2018 - Galleria d&#039;Arte Barbara e Salvioni Design Solutions\" \/>\n<meta property=\"og:description\" content=\"Salvioni ha ospitato la mostra &quot;Serie Armonica Alternata&quot; promossa dalla Galleria d&#039;Arte Barbara Paci di Pietrasanta in occasione del MIART 2018\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Salvioni\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-17T15:04:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-30T16:13:03+00:00\" \/>\n<meta name=\"author\" content=\"Corinna\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Corinna\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/\",\"url\":\"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/\",\"name\":\"Miart 2018 - Galleria d'Arte Barbara e Salvioni Design Solutions\",\"isPartOf\":{\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#website\"},\"datePublished\":\"2018-04-17T15:04:43+00:00\",\"dateModified\":\"2022-12-30T16:13:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/9d68124c2d43e5c54f95f08ee43860f5\"},\"description\":\"Salvioni ha ospitato la mostra \\\"Serie Armonica Alternata\\\" promossa dalla Galleria d'Arte Barbara Paci di Pietrasanta in occasione del MIART 2018\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salvioniarredamenti.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Miart 2018 &#8211; La mostra &#8220;Serie Armonica Alternata&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#website\",\"url\":\"https:\/\/www.salvioniarredamenti.it\/en\/\",\"name\":\"Salvioni\",\"description\":\"Salvioni Arredamenti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salvioniarredamenti.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/9d68124c2d43e5c54f95f08ee43860f5\",\"name\":\"Corinna\",\"url\":\"https:\/\/www.salvioniarredamenti.it\/it\/author\/marketing\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miart 2018 - Galleria d'Arte Barbara e Salvioni Design Solutions","description":"Salvioni ha ospitato la mostra \"Serie Armonica Alternata\" promossa dalla Galleria d'Arte Barbara Paci di Pietrasanta in occasione del MIART 2018","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/","og_locale":"it_IT","og_type":"article","og_title":"Miart 2018 - Galleria d'Arte Barbara e Salvioni Design Solutions","og_description":"Salvioni ha ospitato la mostra \"Serie Armonica Alternata\" promossa dalla Galleria d'Arte Barbara Paci di Pietrasanta in occasione del MIART 2018","og_url":"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/","og_site_name":"Salvioni","article_published_time":"2018-04-17T15:04:43+00:00","article_modified_time":"2022-12-30T16:13:03+00:00","author":"Corinna","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Corinna","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/","url":"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/","name":"Miart 2018 - Galleria d'Arte Barbara e Salvioni Design Solutions","isPartOf":{"@id":"https:\/\/www.salvioniarredamenti.it\/en\/#website"},"datePublished":"2018-04-17T15:04:43+00:00","dateModified":"2022-12-30T16:13:03+00:00","author":{"@id":"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/9d68124c2d43e5c54f95f08ee43860f5"},"description":"Salvioni ha ospitato la mostra \"Serie Armonica Alternata\" promossa dalla Galleria d'Arte Barbara Paci di Pietrasanta in occasione del MIART 2018","breadcrumb":{"@id":"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.salvioniarredamenti.it\/it\/miart-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salvioniarredamenti.it\/it\/"},{"@type":"ListItem","position":2,"name":"Miart 2018 &#8211; La mostra &#8220;Serie Armonica Alternata&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.salvioniarredamenti.it\/en\/#website","url":"https:\/\/www.salvioniarredamenti.it\/en\/","name":"Salvioni","description":"Salvioni Arredamenti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salvioniarredamenti.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/9d68124c2d43e5c54f95f08ee43860f5","name":"Corinna","url":"https:\/\/www.salvioniarredamenti.it\/it\/author\/marketing\/"}]}},"_links":{"self":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts\/16240"}],"collection":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/comments?post=16240"}],"version-history":[{"count":8,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts\/16240\/revisions"}],"predecessor-version":[{"id":16566,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts\/16240\/revisions\/16566"}],"wp:attachment":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/media?parent=16240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/categories?post=16240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/tags?post=16240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}