{"id":50434,"date":"2022-08-05T08:27:57","date_gmt":"2022-08-05T08:27:57","guid":{"rendered":"https:\/\/www.salvioniarredamenti.it\/?p=50434"},"modified":"2022-08-05T08:27:57","modified_gmt":"2022-08-05T08:27:57","slug":"simone-pedretti-marmi","status":"publish","type":"post","link":"https:\/\/www.salvioniarredamenti.it\/it\/simone-pedretti-marmi\/","title":{"rendered":"Simone Pedretti e Salvioni | Una nuova collaborazione d&#8217;eccellenza"},"content":{"rendered":"<p>Salvioni ha dato inizio a una nuova collaborazione con il marchio Simone Pedretti. Di origini trentine, l\u2019azienda nasce per portare avanti un progetto culturale che valorizzi e protegga le ricchezze di questi luoghi e l\u2019immenso patrimonio artigianale in essi custodito.<\/p>\n<p>Il punto di partenza risiede nella lavorazione della pietra nel nord Italia di cui la famiglia Pedretti \u00e8 custode e da cui Simone, fondatore dell\u2019azienda, \u00e8 partito per lanciare il suo nuovo marchio. Le pietre pi\u00f9 rare ed esclusive del mondo trovano qui degna attenzione, trasformandosi in oggetti unici a cavallo fra arredo d\u2019alta gamma e autentiche opere d\u2019arte.<\/p>\n<p>La collezione d\u2019esordio LAPIS parla del territorio trentino e nasce dall\u2019incontro tra manualit\u00e0 e design che il designer Luca Sartori dello studio Superluna ha saputo imprimere in ogni elemento. Il legno pietrificato diviene collezione unica, esclusiva, volta a valorizzare le peculiari venature e gli aspetti secolari che ne hanno segnato la lenta trasformazione.<\/p>\n<p>Simone Pedretti \u00e8 la prima azienda a utilizzare il legno pietrificato per creare arredi di alto livello che uniscono storia, manualit\u00e0 e design in un\u2019unica soluzione di forte suggestione.<\/p>\n<p>La produzione del marchio si declina in tre principali prodotti di punta: Ciocat, Triga e Sfoiat, rispettivamente un set di tavolini per la zona giorno, una panchina da interno per grandi spazi e una libreria free standing, ideale per dividere gli ambienti.<\/p>\n<p>Ognuno di questi elementi cattura per la ricercatezza delle forme nonch\u00e9 l\u2019accurata scelta compiuta su ogni componente al fine di valorizzare ed esaltare al meglio le intrinseche peculiarit\u00e0 dei materiali che la compongono.<\/p>\n<p>Con questa nuova collaborazione Salvioni Design Solutions si augura di poter ancor pi\u00f9 accrescere le proprie proposte d\u2019arredi unici, impossibili da replicare, capaci di soddisfare con la propria singolarit\u00e0 i gusti pi\u00f9 esigenti e offrire uno spunto di autentico valore al panorama di design internazionale. I pezzi di Simone Pedretti non sono infatti soltanto arredo, ma una scelta di stile, una risposta a chi desideri un\u2019autentica punta di diamante all\u2019interno della propria casa o in ambienti dalla forte personalit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salvioni ha dato inizio a una nuova collaborazione con il marchio Simone Pedretti. Di origini trentine, l\u2019azienda nasce per portare avanti un progetto culturale che valorizzi e protegga le ricchezze di questi luoghi e l\u2019immenso patrimonio artigianale in essi custodito. Il punto di partenza risiede nella lavorazione della pietra nel nord Italia di cui la [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[962],"tags":[1391,1389,1388,1390],"class_list":["post-50434","post","type-post","status-publish","format-standard","hentry","category-showroom","tag-legno-pietrificato","tag-marmi","tag-simone-pedretti","tag-vetro-pietrificato"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Simone Pedretti e Salvioni | Una nuova collaborazione d&#039;eccellenza - Salvioni<\/title>\n<meta name=\"description\" content=\"Salvioni ha avviato una nuova collaborazione il marchio Simone Pedretti, marchio d&#039;eccellenza nella creazione di arredi in legno pietrificato\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Simone Pedretti e Salvioni | Una nuova collaborazione d&#039;eccellenza - Salvioni\" \/>\n<meta property=\"og:description\" content=\"Salvioni ha avviato una nuova collaborazione il marchio Simone Pedretti, marchio d&#039;eccellenza nella creazione di arredi in legno pietrificato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/\" \/>\n<meta property=\"og:site_name\" content=\"Salvioni\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-05T08:27:57+00:00\" \/>\n<meta name=\"author\" content=\"@SalvioniArredamenti@\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"@SalvioniArredamenti@\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/\",\"url\":\"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/\",\"name\":\"Simone Pedretti e Salvioni | Una nuova collaborazione d'eccellenza - Salvioni\",\"isPartOf\":{\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#website\"},\"datePublished\":\"2022-08-05T08:27:57+00:00\",\"dateModified\":\"2022-08-05T08:27:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/ada0a5fe0b778c644787af8bb8284bd4\"},\"description\":\"Salvioni ha avviato una nuova collaborazione il marchio Simone Pedretti, marchio d'eccellenza nella creazione di arredi in legno pietrificato\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salvioniarredamenti.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Simone Pedretti e Salvioni | Una nuova collaborazione d&#8217;eccellenza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#website\",\"url\":\"https:\/\/www.salvioniarredamenti.it\/en\/\",\"name\":\"Salvioni\",\"description\":\"Salvioni Arredamenti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salvioniarredamenti.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/ada0a5fe0b778c644787af8bb8284bd4\",\"name\":\"@SalvioniArredamenti@\",\"url\":\"https:\/\/www.salvioniarredamenti.it\/it\/author\/salvioniarredamenti\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Simone Pedretti e Salvioni | Una nuova collaborazione d'eccellenza - Salvioni","description":"Salvioni ha avviato una nuova collaborazione il marchio Simone Pedretti, marchio d'eccellenza nella creazione di arredi in legno pietrificato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/","og_locale":"it_IT","og_type":"article","og_title":"Simone Pedretti e Salvioni | Una nuova collaborazione d'eccellenza - Salvioni","og_description":"Salvioni ha avviato una nuova collaborazione il marchio Simone Pedretti, marchio d'eccellenza nella creazione di arredi in legno pietrificato","og_url":"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/","og_site_name":"Salvioni","article_published_time":"2022-08-05T08:27:57+00:00","author":"@SalvioniArredamenti@","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"@SalvioniArredamenti@","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/","url":"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/","name":"Simone Pedretti e Salvioni | Una nuova collaborazione d'eccellenza - Salvioni","isPartOf":{"@id":"https:\/\/www.salvioniarredamenti.it\/en\/#website"},"datePublished":"2022-08-05T08:27:57+00:00","dateModified":"2022-08-05T08:27:57+00:00","author":{"@id":"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/ada0a5fe0b778c644787af8bb8284bd4"},"description":"Salvioni ha avviato una nuova collaborazione il marchio Simone Pedretti, marchio d'eccellenza nella creazione di arredi in legno pietrificato","breadcrumb":{"@id":"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.salvioniarredamenti.it\/en\/simone-pedretti-marble\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salvioniarredamenti.it\/it\/"},{"@type":"ListItem","position":2,"name":"Simone Pedretti e Salvioni | Una nuova collaborazione d&#8217;eccellenza"}]},{"@type":"WebSite","@id":"https:\/\/www.salvioniarredamenti.it\/en\/#website","url":"https:\/\/www.salvioniarredamenti.it\/en\/","name":"Salvioni","description":"Salvioni Arredamenti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salvioniarredamenti.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/ada0a5fe0b778c644787af8bb8284bd4","name":"@SalvioniArredamenti@","url":"https:\/\/www.salvioniarredamenti.it\/it\/author\/salvioniarredamenti\/"}]}},"_links":{"self":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts\/50434"}],"collection":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/comments?post=50434"}],"version-history":[{"count":2,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts\/50434\/revisions"}],"predecessor-version":[{"id":50460,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts\/50434\/revisions\/50460"}],"wp:attachment":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/media?parent=50434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/categories?post=50434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/tags?post=50434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}