{"id":58518,"date":"2024-05-03T14:31:58","date_gmt":"2024-05-03T13:31:58","guid":{"rendered":"https:\/\/www.salvioniarredamenti.it\/?p=58518"},"modified":"2024-05-03T15:58:04","modified_gmt":"2024-05-03T14:58:04","slug":"intervista-toan-nguyen","status":"publish","type":"post","link":"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/","title":{"rendered":"Intervista | Toan Nguyen"},"content":{"rendered":"<p><strong>Abbiamo intervistato Toan Nguyen, nuovo Direttore Creativo dell\u2019azienda Schiffini. Quest&#8217;anno lo storico marchio di cucine ha scelto di collaborare con Salvioni proponendo in occasione del Fuorisalone 2024 un&#8217;installazione nella vetrina di Via Durini 3, centro nevralgico del design milanese.\u00a0 <\/strong><\/p>\n<p><strong>Protagonista di questo set-up \u00e8 la nuova cucina Cinqueterre, omaggio a Vico Magistretti e imperdibile proposta di catalogo 2024.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Qual \u00e8 la filosofia che hai scelto per affrontare questa nuova avventura?<\/strong><\/p>\n<p>Rilanciare un marchio cos\u00ec importante e storico come Schiffini era ovviamente una sfida, perch\u00e9 il mondo del design \u00e8 cambiato molto negli ultimi tempi e con esso le sue necessit\u00e0. Noi abbiamo cercato di mettere sotto i riflettori tutti gli elementi forti del brand rivisitati in una chiave innovativa e squisitamente italiana, prestando attenzione ai dettagli, ai materiali e al design per creare qualcosa di nuovo e interessante. I temi di oggi sono molto cambiati, il livello generale delle cucine \u00e8 sicuramente molto pi\u00f9 alto e tende ad affinarsi sempre pi\u00f9 spingendo tutti a fare del proprio meglio per rimanere al passo con i tempi.<\/p>\n<p>Ci\u00f2 che invece sembra essere venuto un po\u2019 meno \u00e8 l\u2019attenzione alla matericit\u00e0 che qui abbiamo volutamente riproposto per offrire un\u2019alternativa a cucine incredibilmente funzionali ma fredde, prive di quella componente materiale che ne innalza il valore esperienziale.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Come ti sei comportato con l\u2019eredit\u00e0 di un grande maestro come Vico Magistretti?<\/strong><\/p>\n<p>La sfida pi\u00f9 grande era omaggiare e al contempo rispettare i fondamenti di un design proveniente nientemeno che da Magistretti, padre del marchio Schiffini. Ho quindi cercato di lavorare comprendendo il progetto originale e mantenendone l\u2019essenza pur ritoccandone alcuni parametri in modo chirurgico cos\u00ec da dar vita a una cucina pi\u00f9 contemporanea con una dimensione maggiormente commerciale.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Cosa differenzia creare un progetto di una cucina rispetto ad altre categorie merceologiche?<\/strong><\/p>\n<p>Qualcuno un giorno mi ha detto: quando sai disegnare una cucina, allora sai disegnare tutti i mobili. Personalmente credo sia vero, perch\u00e9 la cucina integra moltissimi elementi diversi fra loro, dagli elettrodomestici alle numerose componenti che danno vita al tutto. Inoltre la cucina necessita di grande flessibilit\u00e0 strutturale perch\u00e9 non ne esiste una uguale all\u2019altra. Progettare questo tipo di arredo vuol dire inseguire due differenti idee: da una parte, creare qualcosa il pi\u00f9 possibile standardizzato e comprensibile in qualunque parte del mondo; dall\u2019altra offrire un\u2019idea su misura capace di adattarsi ai contesti e alle esigenze del cliente. Credo inoltre che sia impossibile trascurare l\u2019elemento materico, ovvero il fatto che nella cucina vivono e vengono racchiusi numerosi elementi naturali come l\u2019acqua, il fuoco, il grasso, l\u2019olio e molto altro che ricorda la vita e la terra. Io ho prestato attenzione a quest\u2019ultimo elemento, inserendo il marmo per creare una base solida e funzionale capace di sostenere tutto il resto.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abbiamo intervistato Toan Nguyen, nuovo Direttore Creativo dell\u2019azienda Schiffini. Quest&#8217;anno lo storico marchio di cucine ha scelto di collaborare con Salvioni proponendo in occasione del Fuorisalone 2024 un&#8217;installazione nella vetrina di Via Durini 3, centro nevralgico del design milanese.\u00a0 Protagonista di questo set-up \u00e8 la nuova cucina Cinqueterre, omaggio a Vico Magistretti e imperdibile proposta [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[960],"tags":[],"class_list":["post-58518","post","type-post","status-publish","format-standard","hentry","category-interviste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Intervista a Toan Nguyen, direttore creativo dell&#039;azienda Schiffini | Cucine<\/title>\n<meta name=\"description\" content=\"Abbiamo intervistato il nuovo direttore creativo dell&#039;azienda Schiffini, Toan Nguyen, la cui nuova cucina Cinqueterre \u00e8 ospite dello showroom di via Durini.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intervista a Toan Nguyen, direttore creativo dell&#039;azienda Schiffini | Cucine\" \/>\n<meta property=\"og:description\" content=\"Abbiamo intervistato il nuovo direttore creativo dell&#039;azienda Schiffini, Toan Nguyen, la cui nuova cucina Cinqueterre \u00e8 ospite dello showroom di via Durini.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/\" \/>\n<meta property=\"og:site_name\" content=\"Salvioni\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-03T13:31:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-03T14:58:04+00:00\" \/>\n<meta name=\"author\" content=\"@SalvioniArredamenti@\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"@SalvioniArredamenti@\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/\",\"url\":\"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/\",\"name\":\"Intervista a Toan Nguyen, direttore creativo dell'azienda Schiffini | Cucine\",\"isPartOf\":{\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#website\"},\"datePublished\":\"2024-05-03T13:31:58+00:00\",\"dateModified\":\"2024-05-03T14:58:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/ada0a5fe0b778c644787af8bb8284bd4\"},\"description\":\"Abbiamo intervistato il nuovo direttore creativo dell'azienda Schiffini, Toan Nguyen, la cui nuova cucina Cinqueterre \u00e8 ospite dello showroom di via Durini.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.salvioniarredamenti.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intervista | Toan Nguyen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#website\",\"url\":\"https:\/\/www.salvioniarredamenti.it\/en\/\",\"name\":\"Salvioni\",\"description\":\"Salvioni Arredamenti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.salvioniarredamenti.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/ada0a5fe0b778c644787af8bb8284bd4\",\"name\":\"@SalvioniArredamenti@\",\"url\":\"https:\/\/www.salvioniarredamenti.it\/it\/author\/salvioniarredamenti\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intervista a Toan Nguyen, direttore creativo dell'azienda Schiffini | Cucine","description":"Abbiamo intervistato il nuovo direttore creativo dell'azienda Schiffini, Toan Nguyen, la cui nuova cucina Cinqueterre \u00e8 ospite dello showroom di via Durini.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/","og_locale":"it_IT","og_type":"article","og_title":"Intervista a Toan Nguyen, direttore creativo dell'azienda Schiffini | Cucine","og_description":"Abbiamo intervistato il nuovo direttore creativo dell'azienda Schiffini, Toan Nguyen, la cui nuova cucina Cinqueterre \u00e8 ospite dello showroom di via Durini.","og_url":"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/","og_site_name":"Salvioni","article_published_time":"2024-05-03T13:31:58+00:00","article_modified_time":"2024-05-03T14:58:04+00:00","author":"@SalvioniArredamenti@","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"@SalvioniArredamenti@","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/","url":"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/","name":"Intervista a Toan Nguyen, direttore creativo dell'azienda Schiffini | Cucine","isPartOf":{"@id":"https:\/\/www.salvioniarredamenti.it\/en\/#website"},"datePublished":"2024-05-03T13:31:58+00:00","dateModified":"2024-05-03T14:58:04+00:00","author":{"@id":"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/ada0a5fe0b778c644787af8bb8284bd4"},"description":"Abbiamo intervistato il nuovo direttore creativo dell'azienda Schiffini, Toan Nguyen, la cui nuova cucina Cinqueterre \u00e8 ospite dello showroom di via Durini.","breadcrumb":{"@id":"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.salvioniarredamenti.it\/it\/intervista-toan-nguyen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.salvioniarredamenti.it\/it\/"},{"@type":"ListItem","position":2,"name":"Intervista | Toan Nguyen"}]},{"@type":"WebSite","@id":"https:\/\/www.salvioniarredamenti.it\/en\/#website","url":"https:\/\/www.salvioniarredamenti.it\/en\/","name":"Salvioni","description":"Salvioni Arredamenti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.salvioniarredamenti.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.salvioniarredamenti.it\/en\/#\/schema\/person\/ada0a5fe0b778c644787af8bb8284bd4","name":"@SalvioniArredamenti@","url":"https:\/\/www.salvioniarredamenti.it\/it\/author\/salvioniarredamenti\/"}]}},"_links":{"self":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts\/58518"}],"collection":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/comments?post=58518"}],"version-history":[{"count":8,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts\/58518\/revisions"}],"predecessor-version":[{"id":58531,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/posts\/58518\/revisions\/58531"}],"wp:attachment":[{"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/media?parent=58518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/categories?post=58518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.salvioniarredamenti.it\/it\/wp-json\/wp\/v2\/tags?post=58518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}